{"id":40,"count":111,"description":"","link":"https:\/\/e-illusion.es\/en\/category\/general-en\/","name":"General","slug":"general-en","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>General archivos - Illusion<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/e-illusion.es\/en\/category\/general-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"General archivos - Illusion\" \/>\n<meta property=\"og:url\" content=\"https:\/\/e-illusion.es\/en\/category\/general-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Illusion\" \/>\n<meta property=\"og:image\" content=\"https:\/\/e-illusion.es\/wp-content\/uploads\/2021\/06\/illusion_rrss.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@e_illusion\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/e-illusion.es\/#organization\",\"name\":\"e-illusion\",\"url\":\"https:\/\/e-illusion.es\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/illusion_marbella\/\",\"https:\/\/www.linkedin.com\/company\/illusion-custom-home-automation-solutions\",\"https:\/\/www.facebook.com\/illusionhomecinema\",\"https:\/\/twitter.com\/e_illusion\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/e-illusion.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/e-illusion.es\/wp-content\/uploads\/2021\/06\/illusion_rrss.png\",\"contentUrl\":\"https:\/\/e-illusion.es\/wp-content\/uploads\/2021\/06\/illusion_rrss.png\",\"width\":400,\"height\":400,\"caption\":\"e-illusion\"},\"image\":{\"@id\":\"https:\/\/e-illusion.es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/e-illusion.es\/#website\",\"url\":\"https:\/\/e-illusion.es\/\",\"name\":\"Illusion\",\"description\":\"Custom Home Automation Solutions\",\"publisher\":{\"@id\":\"https:\/\/e-illusion.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/e-illusion.es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/e-illusion.es\/en\/category\/general-en\/\",\"url\":\"https:\/\/e-illusion.es\/en\/category\/general-en\/\",\"name\":\"General archivos - Illusion\",\"isPartOf\":{\"@id\":\"https:\/\/e-illusion.es\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/e-illusion.es\/en\/category\/general-en\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/e-illusion.es\/en\/category\/general-en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/e-illusion.es\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"General\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"General archivos - Illusion","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/e-illusion.es\/en\/category\/general-en\/","og_locale":"en_US","og_type":"article","og_title":"General archivos - Illusion","og_url":"https:\/\/e-illusion.es\/en\/category\/general-en\/","og_site_name":"Illusion","og_image":[{"width":400,"height":400,"url":"https:\/\/e-illusion.es\/wp-content\/uploads\/2021\/06\/illusion_rrss.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@e_illusion","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/e-illusion.es\/#organization","name":"e-illusion","url":"https:\/\/e-illusion.es\/","sameAs":["https:\/\/www.instagram.com\/illusion_marbella\/","https:\/\/www.linkedin.com\/company\/illusion-custom-home-automation-solutions","https:\/\/www.facebook.com\/illusionhomecinema","https:\/\/twitter.com\/e_illusion"],"logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/e-illusion.es\/#\/schema\/logo\/image\/","url":"https:\/\/e-illusion.es\/wp-content\/uploads\/2021\/06\/illusion_rrss.png","contentUrl":"https:\/\/e-illusion.es\/wp-content\/uploads\/2021\/06\/illusion_rrss.png","width":400,"height":400,"caption":"e-illusion"},"image":{"@id":"https:\/\/e-illusion.es\/#\/schema\/logo\/image\/"}},{"@type":"WebSite","@id":"https:\/\/e-illusion.es\/#website","url":"https:\/\/e-illusion.es\/","name":"Illusion","description":"Custom Home Automation Solutions","publisher":{"@id":"https:\/\/e-illusion.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/e-illusion.es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"CollectionPage","@id":"https:\/\/e-illusion.es\/en\/category\/general-en\/","url":"https:\/\/e-illusion.es\/en\/category\/general-en\/","name":"General archivos - Illusion","isPartOf":{"@id":"https:\/\/e-illusion.es\/#website"},"breadcrumb":{"@id":"https:\/\/e-illusion.es\/en\/category\/general-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/e-illusion.es\/en\/category\/general-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/e-illusion.es\/en\/"},{"@type":"ListItem","position":2,"name":"General"}]}]}},"_links":{"self":[{"href":"https:\/\/e-illusion.es\/en\/wp-json\/wp\/v2\/categories\/40"}],"collection":[{"href":"https:\/\/e-illusion.es\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/e-illusion.es\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/e-illusion.es\/en\/wp-json\/wp\/v2\/posts?categories=40"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}